{"id":7233,"date":"2026-06-29T00:46:42","date_gmt":"2026-06-29T00:46:42","guid":{"rendered":"https:\/\/requesstore.com\/?post_type=product&#038;p=7233"},"modified":"2026-06-29T00:46:42","modified_gmt":"2026-06-29T00:46:42","slug":"blue-royal-dress-2","status":"publish","type":"product","link":"https:\/\/requesstore.com\/index.php\/product\/blue-royal-dress-2\/","title":{"rendered":"Blue royal dress"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Size: Shein XL\/large fit<\/p>\n","protected":false},"featured_media":7235,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_cat":[207],"product_tag":[],"class_list":["post-7233","product","type-product","status-publish","has-post-thumbnail","product_cat-dresses","first","instock","shipping-taxable","purchasable","product-type-simple","col-xs-6 col-sm-4","col-mf-5","un-5-cols"],"_links":{"self":[{"href":"https:\/\/requesstore.com\/index.php\/wp-json\/wp\/v2\/product\/7233","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/requesstore.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/requesstore.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/requesstore.com\/index.php\/wp-json\/wp\/v2\/comments?post=7233"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/requesstore.com\/index.php\/wp-json\/wp\/v2\/media\/7235"}],"wp:attachment":[{"href":"https:\/\/requesstore.com\/index.php\/wp-json\/wp\/v2\/media?parent=7233"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/requesstore.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=7233"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/requesstore.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=7233"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}